{"id":1556,"date":"2026-06-30T07:32:31","date_gmt":"2026-06-30T07:32:31","guid":{"rendered":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/"},"modified":"2026-06-30T07:32:31","modified_gmt":"2026-06-30T07:32:31","slug":"siva-narayanan","status":"publish","type":"people","link":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/","title":{"rendered":"Siva Narayanan"},"content":{"rendered":"","protected":false},"author":1,"featured_media":1557,"template":"","people_category":[22],"people_tag":[],"chapters":[],"class_list":["post-1556","people","type-people","status-publish","has-post-thumbnail","hentry","people_category-volunteers"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Siva Narayanan - AIBoomi<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siva Narayanan - AIBoomi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/\" \/>\n<meta property=\"og:site_name\" content=\"AIBoomi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SaaSBoomi\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-content\/uploads\/2026\/06\/Screenshot-2025-02-10-at-6.53.44-PM-png.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"554\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AIBoomi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/people\\\/siva-narayanan\\\/\",\"url\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/people\\\/siva-narayanan\\\/\",\"name\":\"Siva Narayanan - AIBoomi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/people\\\/siva-narayanan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/people\\\/siva-narayanan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2025-02-10-at-6.53.44-PM-png.webp\",\"datePublished\":\"2026-06-30T07:32:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/people\\\/siva-narayanan\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/people\\\/siva-narayanan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/people\\\/siva-narayanan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2025-02-10-at-6.53.44-PM-png.webp\",\"contentUrl\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2025-02-10-at-6.53.44-PM-png.webp\",\"width\":554,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/people\\\/siva-narayanan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"People\",\"item\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/people\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Siva Narayanan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/#website\",\"url\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/\",\"name\":\"AIBoomi\",\"description\":\"The world&#039;s largest community for AI founders and product builders\",\"publisher\":{\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/#organization\",\"name\":\"AIBoomi\",\"url\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-favicon-192x192-1.webp\",\"contentUrl\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-favicon-192x192-1.webp\",\"width\":192,\"height\":192,\"caption\":\"AIBoomi\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.matsio.com\\\/matsio\\\/aiboomi-new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SaaSBoomi\\\/\",\"https:\\\/\\\/x.com\\\/AIBoomi\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Siva Narayanan - AIBoomi","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Siva Narayanan - AIBoomi","og_url":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/","og_site_name":"AIBoomi","article_publisher":"https:\/\/www.facebook.com\/SaaSBoomi\/","og_image":[{"width":554,"height":678,"url":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-content\/uploads\/2026\/06\/Screenshot-2025-02-10-at-6.53.44-PM-png.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@AIBoomi","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/","url":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/","name":"Siva Narayanan - AIBoomi","isPartOf":{"@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/#primaryimage"},"image":{"@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-content\/uploads\/2026\/06\/Screenshot-2025-02-10-at-6.53.44-PM-png.webp","datePublished":"2026-06-30T07:32:31+00:00","breadcrumb":{"@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/#primaryimage","url":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-content\/uploads\/2026\/06\/Screenshot-2025-02-10-at-6.53.44-PM-png.webp","contentUrl":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-content\/uploads\/2026\/06\/Screenshot-2025-02-10-at-6.53.44-PM-png.webp","width":554,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/siva-narayanan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/"},{"@type":"ListItem","position":2,"name":"People","item":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/people\/"},{"@type":"ListItem","position":3,"name":"Siva Narayanan"}]},{"@type":"WebSite","@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/#website","url":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/","name":"AIBoomi","description":"The world&#039;s largest community for AI founders and product builders","publisher":{"@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/#organization","name":"AIBoomi","url":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/#\/schema\/logo\/image\/","url":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-content\/uploads\/2026\/07\/cropped-favicon-192x192-1.webp","contentUrl":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-content\/uploads\/2026\/07\/cropped-favicon-192x192-1.webp","width":192,"height":192,"caption":"AIBoomi"},"image":{"@id":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SaaSBoomi\/","https:\/\/x.com\/AIBoomi"]}]}},"_links":{"self":[{"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/people\/1556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/people"}],"about":[{"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/types\/people"}],"author":[{"embeddable":true,"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/people\/1556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/media\/1557"}],"wp:attachment":[{"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/media?parent=1556"}],"wp:term":[{"taxonomy":"people_category","embeddable":true,"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/people_category?post=1556"},{"taxonomy":"people_tag","embeddable":true,"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/people_tag?post=1556"},{"taxonomy":"chapters","embeddable":true,"href":"https:\/\/dev.matsio.com\/matsio\/aiboomi-new\/wp-json\/wp\/v2\/chapters?post=1556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}